{"id":3231,"date":"2015-06-11T17:30:04","date_gmt":"2015-06-11T16:30:04","guid":{"rendered":"https:\/\/la-bergere.fr\/?p=3231"},"modified":"2015-06-11T17:30:04","modified_gmt":"2015-06-11T16:30:04","slug":"des-champagnes-rares-dominent-les-encheres-prevues-fin-juin","status":"publish","type":"post","link":"https:\/\/la-bergere.fr\/zh\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/","title":{"rendered":"\u7a00\u6709\u9999\u69df\u4e3b\u5bfc\u5b9a\u4e8e 6 \u6708\u5e95\u4e3e\u884c\u7684\u62cd\u5356\u4f1a"},"content":{"rendered":"<p style=\"text-align: justify;\">\u5728 6 \u6708\u5e95\u4e3e\u529e\u7684\u62cd\u5356\u4f1a\u4e0a\uff0c\u82cf\u5bcc\u6bd4\u548c Hart Davis Hart \u5c06\u63d0\u4f9b\u7a00\u6709\u73cd\u85cf\u7684\u8457\u540d\u9999\u69df\uff0c\u4ee5\u53ca\u4e00\u7cfb\u5217\u5176\u4ed6\u4f18\u8d28\u8461\u8404\u9152\u3002<\/p>\n<p style=\"text-align: justify;\">\u82cf\u5bcc\u6bd4\u5c06\u4e8e 6 \u6708 17 \u65e5\u5728\u4f26\u6566\u4e3e\u529e\u62cd\u5356\u4f1a\uff0c\u5c4a\u65f6\u5c06\u63a8\u51fa 1979 \u5e74\u81f3 1998 \u5e74\u7684 Krug Clos du Mesnil\uff08\u7167\u7247\uff09\u30011985\u30011991 \u548c 1995 \u5e74\u4efd\u7684 Nicolas Fran\u00e7ois Billecart\uff0c\u8fd9\u662f Billecart-Salmon \u9152\u5e84\u7684\u4e00\u6b3e\u7a00\u6709\u7279\u917f\uff0c\u4ee5\u53ca\u5404\u79cd\u5f62\u5f0f\u7684\u5404\u79cd\u9999\u69df\uff0c\u5176\u4e2d\u4e00\u4e9b\u53ef\u4ee5\u8ffd\u6eaf\u5230 1960 \u5e74\u4ee3\uff1aLouis Roederer\u3001Clos du Mesnil\u3001Dom P\u00e9rignon \u0152noth\u00e8que \u548c Comtes de Champagne de Taittinger\u3002<\/p>\n<p style=\"text-align: justify;\">\u5c31\u5176\u672c\u8eab\u800c\u8a00\uff0cHart Davis Hart \u62cd\u5356\u4f1a\u5c06\u4e8e 6 \u6708 26 \u65e5\u81f3 27 \u65e5\u5728\u829d\u52a0\u54e5\u4e3e\u884c\uff0c\u5c4a\u65f6\u5c06\u5305\u62ec\u5927\u91cf\u76f4\u63a5\u6765\u81ea\u9999\u69df\u9152\u5382\u5730\u7a96\u7684 Dom P\u00e9rignon \u201cP3\u201d\uff1a\u4e09\u74f6 1966 \u5e74\u7684\u5927\u9152\u74f6\uff0c12 \u74f6 1971 \u5e74\u7684\u8461\u8404\u9152\uff08\u5410\u51fa\u7684\uff09 2013 \u5e74\uff09\u548c\u4e09\u74f6 1985 \u5e74\u6843\u7ea2\u8461\u8404\u9152\uff082008 \u5e74\u9664\u6e23\uff09\u7b49\u3002<\/p>\n<p style=\"text-align: justify;\">\u52c3\u826e\u7b2c\u4e5f\u5c06\u5728\u4e24\u6b21\u9500\u552e\u4e2d\u5360\u636e\u663e\u7740\u4f4d\u7f6e\u3002\u82cf\u5bcc\u6bd4\u5c06\u63d0\u4f9b\u6765\u81ea\u201c\u8457\u540d\u201d\u7c73\u5176\u6797\u661f\u7ea7\u9910\u5385\u5730\u7a96\u7684\u7f57\u66fc\u5c3c\u5eb7\u5e1d\u9152\u5e84\u548c\u52d2\u5f17\u83b1\u592b\u9152\u5e84\uff0c\u4ee5\u53ca\u52d2\u534e\u9152\u5e84\u3001\u62c9\u4e30\u4f2f\u7235\u3001\u6c83\u53e4\u4f2f\u7235\u3001\u963f\u5c14\u8292\u5362\u68ad\u548c\u4ea8\u5229\u8d3e\u8036\u9152\u5e84\u3002\u5176\u4e2d\u8bb8\u591a\u540d\u5b57\u4e5f\u5c06\u51fa\u73b0\u5728 Hart Davis Hart \u62cd\u5356\u4f1a\u4e0a\u3002<\/p>\n<p style=\"text-align: justify;\">\u82cf\u5bcc\u6bd4\u7684\u62cd\u5356\u8fd8\u5c06\u5305\u62ec\u201c\u5728\u62cd\u5356\u4f1a\u4e0a\u7f55\u89c1\u201d\u7684\u610f\u5927\u5229\u8461\u8404\u9152 Il Caberlot\uff0c\u4ee5\u53ca 1937-1988 \u5e74\u4efd\u7684 Ch\u00e2teau d&#039;Yquem\uff082,800-3,600 \u82f1\u9551\uff0c\u5373 3,800 \u81f3 4,900 \u6b27\u5143\uff09\u548c\u4e00\u74f6 Taylor 1945 \u6ce2\u7279\u9152.<\/p>\n<p style=\"text-align: justify;\">\u5c31 Hart Davis Hart \u800c\u8a00\uff0c\u5b83\u5c06\u63d0\u4f9b\u4e00\u4e2a\u5305\u542b 17 \u4e2a\u5e74\u4efd\u7684\u5578\u9e70\uff08\u539f\u88c5\uff09\u7684\u201c\u60ca\u4eba\u201d\u7cfb\u5217\u4ee5\u53ca\u4e00\u4e2a\u5305\u542b 25 \u4e2a\u5e74\u4efd\u7684 Unico \u7684\u201c\u767e\u79d1\u5168\u4e66\u201d\u3002<\/p>\n<p style=\"text-align: justify;\">2015 \u5e74 6 \u6708 8 \u65e5<\/p>\n<p style=\"text-align: justify;\">\u9c81\u4f2f\u7279\u00b7\u7c73\u52d2<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.thedrinksbusiness.com\/2015\/06\/rare-champagne-dominates-late-june-auctions\/\" target=\"_blank\">\u996e\u6599\u4e1a\u52a1<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors d&rsquo;ench\u00e8res organis\u00e9es fin juin, Sotheby&rsquo;s et Hart Davis Hart proposeront \u00e0 la vente des collections rares de champagnes de renom, ainsi qu&rsquo;une ribambelle d&rsquo;autres grands vins. Sotheby&rsquo;s organisera sa vente le 17 juin \u00e0 Londres et y proposera une verticale de Krug Clos du Mesnil allant de 1979 \u00e0 1998 (photo), les mill\u00e9simes 1985, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin - La Berg\u00e8re<\/title>\n<meta name=\"description\" content=\"La Berg\u00e8re - Grands Vins est un n\u00e9gociant en vin pour les professionnels - Vente et Achat de grands vins et grands crus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/la-bergere.fr\/zh\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin - La Berg\u00e8re\" \/>\n<meta property=\"og:description\" content=\"La Berg\u00e8re - Grands Vins est un n\u00e9gociant en vin pour les professionnels - Vente et Achat de grands vins et grands crus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/la-bergere.fr\/zh\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/\" \/>\n<meta property=\"og:site_name\" content=\"La Berg\u00e8re\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-11T16:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/la-bergere.fr\/wp-content\/uploads\/2014\/07\/bkz-header15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"299\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/\"},\"author\":{\"name\":\"webmaster\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/#\\\/schema\\\/person\\\/e639f8c184479ec5fb4cd6014b7ca2d6\"},\"headline\":\"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin\",\"datePublished\":\"2015-06-11T16:30:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/\"},\"wordCount\":306,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/la-bergere.fr\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/bkz-header15.jpg\",\"articleSection\":[\"A la une\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/\",\"url\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/\",\"name\":\"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin - La Berg\u00e8re\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/la-bergere.fr\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/bkz-header15.jpg\",\"datePublished\":\"2015-06-11T16:30:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/#\\\/schema\\\/person\\\/e639f8c184479ec5fb4cd6014b7ca2d6\"},\"description\":\"La Berg\u00e8re - Grands Vins est un n\u00e9gociant en vin pour les professionnels - Vente et Achat de grands vins et grands crus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/la-bergere.fr\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/bkz-header15.jpg\",\"contentUrl\":\"https:\\\/\\\/la-bergere.fr\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/bkz-header15.jpg\",\"width\":1024,\"height\":299},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/la-bergere.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/#website\",\"url\":\"https:\\\/\\\/la-bergere.fr\\\/\",\"name\":\"La Berg\u00e8re\",\"description\":\"N\u00e9goce de grands crus et vins fins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/la-bergere.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/la-bergere.fr\\\/#\\\/schema\\\/person\\\/e639f8c184479ec5fb4cd6014b7ca2d6\",\"name\":\"webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af4969f3a29fa9622de7c1d92034da44848eed035ff48687cdc235e6265587ae?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af4969f3a29fa9622de7c1d92034da44848eed035ff48687cdc235e6265587ae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af4969f3a29fa9622de7c1d92034da44848eed035ff48687cdc235e6265587ae?s=96&d=mm&r=g\",\"caption\":\"webmaster\"},\"url\":\"https:\\\/\\\/la-bergere.fr\\\/zh\\\/author\\\/la-bergere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin - La Berg\u00e8re","description":"La Berg\u00e8re - Grands Vins est un n\u00e9gociant en vin pour les professionnels - Vente et Achat de grands vins et grands crus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/la-bergere.fr\/zh\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/","og_locale":"zh_CN","og_type":"article","og_title":"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin - La Berg\u00e8re","og_description":"La Berg\u00e8re - Grands Vins est un n\u00e9gociant en vin pour les professionnels - Vente et Achat de grands vins et grands crus.","og_url":"https:\/\/la-bergere.fr\/zh\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/","og_site_name":"La Berg\u00e8re","article_published_time":"2015-06-11T16:30:04+00:00","og_image":[{"width":1024,"height":299,"url":"https:\/\/la-bergere.fr\/wp-content\/uploads\/2014\/07\/bkz-header15.jpg","type":"image\/jpeg"}],"author":"webmaster","twitter_misc":{"\u4f5c\u8005":"webmaster","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#article","isPartOf":{"@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/"},"author":{"name":"webmaster","@id":"https:\/\/la-bergere.fr\/#\/schema\/person\/e639f8c184479ec5fb4cd6014b7ca2d6"},"headline":"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin","datePublished":"2015-06-11T16:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/"},"wordCount":306,"commentCount":0,"image":{"@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#primaryimage"},"thumbnailUrl":"https:\/\/la-bergere.fr\/wp-content\/uploads\/2014\/07\/bkz-header15.jpg","articleSection":["A la une"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/","url":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/","name":"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin - La Berg\u00e8re","isPartOf":{"@id":"https:\/\/la-bergere.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#primaryimage"},"image":{"@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#primaryimage"},"thumbnailUrl":"https:\/\/la-bergere.fr\/wp-content\/uploads\/2014\/07\/bkz-header15.jpg","datePublished":"2015-06-11T16:30:04+00:00","author":{"@id":"https:\/\/la-bergere.fr\/#\/schema\/person\/e639f8c184479ec5fb4cd6014b7ca2d6"},"description":"La Berg\u00e8re - Grands Vins est un n\u00e9gociant en vin pour les professionnels - Vente et Achat de grands vins et grands crus.","breadcrumb":{"@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#primaryimage","url":"https:\/\/la-bergere.fr\/wp-content\/uploads\/2014\/07\/bkz-header15.jpg","contentUrl":"https:\/\/la-bergere.fr\/wp-content\/uploads\/2014\/07\/bkz-header15.jpg","width":1024,"height":299},{"@type":"BreadcrumbList","@id":"https:\/\/la-bergere.fr\/des-champagnes-rares-dominent-les-encheres-prevues-fin-juin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/la-bergere.fr\/"},{"@type":"ListItem","position":2,"name":"Des champagnes rares dominent les ench\u00e8res pr\u00e9vues fin juin"}]},{"@type":"WebSite","@id":"https:\/\/la-bergere.fr\/#website","url":"https:\/\/la-bergere.fr\/","name":"\u7267\u7f8a\u5973","description":"\u7279\u7ea7\u8461\u8404\u9152\u548c\u4f18\u8d28\u8461\u8404\u9152\u7684\u8d38\u6613","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/la-bergere.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/la-bergere.fr\/#\/schema\/person\/e639f8c184479ec5fb4cd6014b7ca2d6","name":"webmaster","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/af4969f3a29fa9622de7c1d92034da44848eed035ff48687cdc235e6265587ae?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af4969f3a29fa9622de7c1d92034da44848eed035ff48687cdc235e6265587ae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af4969f3a29fa9622de7c1d92034da44848eed035ff48687cdc235e6265587ae?s=96&d=mm&r=g","caption":"webmaster"},"url":"https:\/\/la-bergere.fr\/zh\/author\/la-bergere\/"}]}},"_links":{"self":[{"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/posts\/3231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/comments?post=3231"}],"version-history":[{"count":1,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/posts\/3231\/revisions"}],"predecessor-version":[{"id":3232,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/posts\/3231\/revisions\/3232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/media\/2200"}],"wp:attachment":[{"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/media?parent=3231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/categories?post=3231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-bergere.fr\/zh\/wp-json\/wp\/v2\/tags?post=3231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}